{"id":43,"date":"2017-04-10T10:31:26","date_gmt":"2017-04-10T18:31:26","guid":{"rendered":"http:\/\/eddornelas.com\/?page_id=43"},"modified":"2017-04-12T00:56:40","modified_gmt":"2017-04-12T08:56:40","slug":"apps","status":"publish","type":"page","link":"https:\/\/eddornelas.com\/en\/apps\/","title":{"rendered":"Apps Created"},"content":{"rendered":"<p><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"166\" height=\"300\" src=\"https:\/\/eddornelas.com\/wp-content\/uploads\/2017\/04\/done2-166x300.png\" class=\"vc_single_image-img attachment-medium\" alt=\"\" srcset=\"https:\/\/eddornelas.com\/wp-content\/uploads\/2017\/04\/done2-166x300.png 166w, https:\/\/eddornelas.com\/wp-content\/uploads\/2017\/04\/done2.png 325w\" sizes=\"(max-width: 166px) 100vw, 166px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<h2 style=\"font-size: 22px;text-align: left;font-family:Abril Fatface;font-weight:400;font-style:normal\" class=\"vc_custom_heading\" ><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.prometeoparallels.donelohace\">Done - Limpieza<\/a><\/h2>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>App that permits hire house cleaners.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"156\" height=\"300\" src=\"https:\/\/eddornelas.com\/wp-content\/uploads\/2017\/04\/edd2-156x300.png\" class=\"vc_single_image-img attachment-medium\" alt=\"\" srcset=\"https:\/\/eddornelas.com\/wp-content\/uploads\/2017\/04\/edd2-156x300.png 156w, https:\/\/eddornelas.com\/wp-content\/uploads\/2017\/04\/edd2.png 328w\" sizes=\"(max-width: 156px) 100vw, 156px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<h2 style=\"font-size: 22px;text-align: left;font-family:Abril Fatface;font-weight:400;font-style:normal\" class=\"vc_custom_heading\" ><a href=\"#\">Soon<\/a><\/h2>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Soon.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"156\" height=\"300\" src=\"https:\/\/eddornelas.com\/wp-content\/uploads\/2017\/04\/edd2-156x300.png\" class=\"vc_single_image-img attachment-medium\" alt=\"\" srcset=\"https:\/\/eddornelas.com\/wp-content\/uploads\/2017\/04\/edd2-156x300.png 156w, https:\/\/eddornelas.com\/wp-content\/uploads\/2017\/04\/edd2.png 328w\" sizes=\"(max-width: 156px) 100vw, 156px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<h2 style=\"font-size: 22px;text-align: left;font-family:Abril Fatface;font-weight:400;font-style:normal\" class=\"vc_custom_heading\" ><a href=\"#\">Soon<\/a><\/h2>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Soon.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/p>","protected":false},"excerpt":{"rendered":"Done - Limpieza App that permits hire house cleaners. Soon Soon. Soon Soon.","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.9.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apps Created - eddOrnelas<\/title>\n<link rel=\"canonical\" href=\"https:\/\/eddornelas.com\/en\/apps\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apps Created - eddOrnelas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eddornelas.com\/en\/apps\/\" \/>\n<meta property=\"og:site_name\" content=\"eddOrnelas\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-12T08:56:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"1 minute\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eddornelas.com\/en\/#website\",\"url\":\"https:\/\/eddornelas.com\/en\/\",\"name\":\"eddOrnelas\",\"description\":\"Web &amp; Game Development\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/eddornelas.com\/en\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eddornelas.com\/en\/apps\/#webpage\",\"url\":\"https:\/\/eddornelas.com\/en\/apps\/\",\"name\":\"Apps Created - eddOrnelas\",\"isPartOf\":{\"@id\":\"https:\/\/eddornelas.com\/en\/#website\"},\"datePublished\":\"2017-04-10T18:31:26+00:00\",\"dateModified\":\"2017-04-12T08:56:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eddornelas.com\/en\/apps\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eddornelas.com\/en\/apps\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eddornelas.com\/en\/apps\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eddornelas.com\/en\/\",\"url\":\"https:\/\/eddornelas.com\/en\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eddornelas.com\/en\/apps\/\",\"url\":\"https:\/\/eddornelas.com\/en\/apps\/\",\"name\":\"Apps Created\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/eddornelas.com\/en\/wp-json\/wp\/v2\/pages\/43"}],"collection":[{"href":"https:\/\/eddornelas.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eddornelas.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eddornelas.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eddornelas.com\/en\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":10,"href":"https:\/\/eddornelas.com\/en\/wp-json\/wp\/v2\/pages\/43\/revisions"}],"predecessor-version":[{"id":196,"href":"https:\/\/eddornelas.com\/en\/wp-json\/wp\/v2\/pages\/43\/revisions\/196"}],"wp:attachment":[{"href":"https:\/\/eddornelas.com\/en\/wp-json\/wp\/v2\/media?parent=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}